{"id":3686,"date":"2021-09-29T10:00:48","date_gmt":"2021-09-29T08:00:48","guid":{"rendered":"https:\/\/veterinariveteros.com\/?p=3686"},"modified":"2021-09-30T18:19:15","modified_gmt":"2021-09-30T16:19:15","slug":"entrevista-a-alvaro-molins","status":"publish","type":"post","link":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/","title":{"rendered":"Entrevista a \u00c1lvaro Molins"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La opini\u00f3n de los gerentes de cl\u00ednicas veterinarias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa de servicios de gesti\u00f3n estrat\u00e9gica y marketing digital Myvetpet Consulting entrevista a \u00c1lvaro Molins, gerente de Cl\u00ednica Veterinaria Veteros de Barcelona que forma parte del Grupo Riera Alta. Mediante esta entrevista damos voz a los gerentes de cl\u00ednicas veterinarias y divulgamos parte del trabajo que realizan al frente de sus negocios, poniendo en valor el esfuerzo diario que exige esta dif\u00edcil profesi\u00f3n y que hacen de la veterinaria un servicio esencial para la sociedad moderna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211; La vocaci\u00f3n<\/strong><br><strong>\u00bfCu\u00e1ndo decidiste que quer\u00edas ser gerente de una cl\u00ednica veterinaria y c\u00f3mo se materializ\u00f3?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya s\u00e9 que suena a t\u00f3pico, pero ya desde bien peque\u00f1o me ten\u00edan enamorado los animales, era el t\u00edpico ni\u00f1o que no dejaban tener perro pero que se las apa\u00f1aba para tener todo tipo de animales en casa. Ya de mayor empec\u00e9 a estudiar Auxiliar Veterinario motivado por mi hermana mayor. Finalizada la academia, tuve la suerte de entrar a trabajar en el Hospital Veterinario Riera Alta. All\u00ed desempe\u00f1\u00e9 varias labores aprendiendo un poco de todo en el sector. A la vez me segu\u00ed formando con cursos relacionados tanto con la salud animal como con temas de gesti\u00f3n y marketing en cl\u00ednicas veterinarias. Con el tiempo decid\u00ed dar un paso m\u00e1s all\u00e1 y junto con Javier Sanchez de Rojas, Gerente del Hospital Veterinario Riera Alta, ampliamos el grupo Riera Alta con la Cl\u00ednica Veterinaria Veteros. Desde entonces ha llovido un poco pero sigo con la misma ilusi\u00f3n del primer d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211;&nbsp;La cl\u00ednica<\/strong><br><strong>\u00bfPor qu\u00e9 decides instalar una cl\u00ednica veterinaria en Barcelona?<br>Cu\u00e9ntanos que cambios has realizado desde los inicios y que servicios ofreces actualmente a tus clientes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo decidimos por log\u00edstica. La cl\u00ednica forma parte del grupo Riera Alta y, por situaci\u00f3n, era la mejor opci\u00f3n para poder ofrecer tambi\u00e9n a nuestros clientes todos los servicios de especialidad que ofrece el Hospital como hospitalizaci\u00f3n, traumatolog\u00eda, cardiolog\u00eda, etc. Emprendimos esta aventura Yolanda Brils como veterinaria y yo como ATV. Los principios&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; fueron m\u00e1s duros, ya que todo el trabajo de gesti\u00f3n lo llevaba a cabo al terminar mi jornada laboral. Poco a poco ampliamos personal incorporando a Jes\u00fas Parro como veterinario y a Soraya Mart\u00edn como ATV. Con estas incorporaciones mejoramos nuestro servicio de atenci\u00f3n al cliente y por otra parte reducimos el tiempo de espera tanto en visitas como en cirug\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el lado t\u00e9cnico, adquirimos un equipo de radiolog\u00eda digital y un ec\u00f3grafo con los que mejoramos nuestro diagn\u00f3stico por imagen. De igual forma actualizamos nuestro servicio de laboratorio con la adquisici\u00f3n de un completo y avanzado equipo de laboratorio. Con ello podemos realizar multitud de pruebas para dar con el diagn\u00f3stico m\u00e1s r\u00e1pido y concreto posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ampliamos nuestro espacio dedicado a alimentaci\u00f3n, complementos y juguetes. Ofrecemos todo lo necesario para mantener la mejor calidad de vida de las mascotas. Nos esforzamos en llevar a cabo una adecuada medicina preventiva mediante revisiones, vacunas, desparasitaciones y alimentaci\u00f3n adecuada a cada animal. Actualmente disponemos de servicio de consulta general, cirug\u00eda, radiolog\u00eda, ecograf\u00eda, anal\u00edtica y tratamientos oncol\u00f3gicos.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"076703f814d3e673bcfc1a9f5d1e3cbb\"><img decoding=\"async\" width=\"1980\" height=\"1320\" loading=\"lazy\" src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-instalaciones-laboratorio-2-1.jpg\" alt=\"\" class=\"wp-image-3054\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"bdee046162a77f68ee197db5833b71da\"><img decoding=\"async\" width=\"1000\" height=\"667\" loading=\"lazy\" src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-inicio-instalaciones-1.jpg\" alt=\"\" class=\"wp-image-2973\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211; El equipo<\/strong><br><strong>&nbsp;\u00bfCu\u00e1nto tiempo lleva el equipo contigo? \u00bfCu\u00e1les son sus funciones?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yolanda lleva con nosotros desde 2014, a\u00f1o en que empezamos en Veteros, Jes\u00fas y Soraya llevan dos a\u00f1os formando parte de nuestro equipo. Soraya se encarga de la atenci\u00f3n al cliente en la recepci\u00f3n, pedidos y control de stocks, as\u00ed como de ayudar a los veterinarios en todo lo que se requiera, ya sea para realizar anal\u00edticas como radiograf\u00edas y cirug\u00edas. Yolanda y Jes\u00fas coordinan su trabajo como veterinarios tanto para realizar visitas como cirug\u00edas, de manera que se puedan atender con la menor demora posible. Mi funci\u00f3n a d\u00eda de hoy es de apoyo a Soraya para suplir su puesto cuando es requerida por los veterinarios y as\u00ed poder dedicar el resto del tiempo a todos los temas administrativos de la cl\u00ednica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211; La gesti\u00f3n del tiempo<\/strong><br><strong>\u00bfC\u00f3mo organizas las principales tareas de la cl\u00ednica veterinaria para que los clientes queden satisfechos de vuestros servicios, dedicar tiempo a la gesti\u00f3n de la empresa y adem\u00e1s hacer de pap\u00e1??<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pues la verdad es que, como todo, al principio fue durillo y complicado. Adem\u00e1s, hay que tener en cuenta que los temas administrativos y de gesti\u00f3n me pillaba todo de nuevo, pero mi socio Javier me apoy\u00f3 en todo y lo fuimos superando. Hoy en d\u00eda todo es mucho m\u00e1s f\u00e1cil gracias al gran equipo que tenemos.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"a530ee3352555d262207d68a687fd76a\"><img decoding=\"async\" width=\"1000\" height=\"667\" loading=\"lazy\" src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-inicio-equipo-1.jpg\" alt=\"\" class=\"wp-image-2965\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"2a369174ace049a029b41dcf2a042a59\"><img decoding=\"async\" width=\"1980\" height=\"1320\" loading=\"lazy\" src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-instalaciones-radio-1.jpg\" alt=\"\" class=\"wp-image-3056\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211; La gesti\u00f3n estrat\u00e9gica<\/strong><br><strong>Eres un gerente de cl\u00ednica veterinaria que sabemos dedicas parte de tu tiempo a analizar qu\u00e9 cosas pasan y por qu\u00e9 pasan en tu negocio. \u00bfQu\u00e9 beneficios te aporta dedicar parte de tu tiempo a la gesti\u00f3n estrat\u00e9gica en la cl\u00ednica veterinaria?<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era un campo totalmente nuevo para m\u00ed. Empec\u00e9 a adquirir ciertos conocimientos sobre ello con diversos cursos de gesti\u00f3n que impart\u00edan tanto laboratorios como distribuidores. Viendo la importancia de este tema en la evoluci\u00f3n de un negocio, optamos por un asesor externo que nos hizo tener una visi\u00f3n de la cl\u00ednica m\u00e1s estrat\u00e9gica. Desde entonces, dedicamos tiempo a organizar acciones que beneficien tanto a la cl\u00ednica como a nuestros clientes, como campa\u00f1as, promociones y descuentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211; La visibilidad en internet<br>\u00bfQu\u00e9 piensas de estar en internet? \u00bfNecesidad u obligaci\u00f3n?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A d\u00eda de hoy para nosotros considero que internet es una necesidad para poder transmitir toda la informaci\u00f3n veraz que requieren nuestros clientes y una obligaci\u00f3n, cara a nuestros clientes, para poder mantenerles al d\u00eda de cualquier avance de nuestro sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet \u2013 La comunicaci\u00f3n<br>\u00bfC\u00f3mo entiendes que debe ser la comunicaci\u00f3n entre la cl\u00ednica veterinaria y los propietarios de mascotas? Hemos visto que tu cl\u00ednica est\u00e1 entre las primeras de Barcelona en las excelentes opiniones que dejan vuestros clientes en internet, un 4,7 en Google, es el sue\u00f1o deseado para muchos centros. \u00bfC\u00f3mo lo haces?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet es una via de comunicaci\u00f3n imprescindible hoy en d\u00eda para contactar con el cliente. Pero donde verdaderamente se hace una labor de comunicaci\u00f3n es en el trato personal en el centro. La opini\u00f3n que puedan tener sobre nosotros, a parte de los servicios que podamos ofrecer, se debe al equipo de trabajo del centro. Nosotros siempre vamos a tratar, cuidar e informar a nuestros pacientes como si se tratase de nuestras propias mascotas. Intentamos ponernos en el lugar del propietario pero sin dejar de lado nuestro papel m\u00e1s cl\u00ednico y profesional. A veces es complicado pero buscar siempre ese equilibro creo que es la clave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet \u2013 El sector<br>\u00bfCu\u00e1l es tu opini\u00f3n acerca de d\u00f3nde se dirige este sector? \u00bfPiensas que estamos en una transformaci\u00f3n de este tipo de negocios hacia una mayor profesionalizaci\u00f3n?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda alguna. El sector va a la par con lo que reclama una sociedad cada vez m\u00e1s consciente de los avances cient\u00edficos y de la mayor aceptaci\u00f3n de nuestras mascotas en todos los aspectos. Cada d\u00eda son m\u00e1s las personas que tienen una mascota como un individuo m\u00e1s de la familia y quieren para ellas lo mismo que exigen para cualquier otro miembro de la familia. Ello nos obliga a las cl\u00ednicas a disponer o poder ofrecer los servicios de especializaci\u00f3n que el animal necesite en todo momento. La formaci\u00f3n del personal es una de las bases fundamentales de esta transformaci\u00f3n del sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myvetpet &#8211; <\/strong>Como siempre, es un placer compartir contigo un poco de ese tan valioso tiempo y te agradecemos esta aportaci\u00f3n que nos has hecho hoy.<strong><br><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c1lvaro Molins, Cl\u00ednica Veterinaria Veteros de Barcelona<br>David Vargas, Myvetpet Consulting<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La opini\u00f3n de los gerentes de cl\u00ednicas veterinarias La empresa de servicios de gesti\u00f3n estrat\u00e9gica y marketing digital Myvetpet Consulting entrevista a \u00c1lvaro Molins, gerente de Cl\u00ednica Veterinaria Veteros de Barcelona que forma parte del Grupo Riera Alta. Mediante esta entrevista damos voz a los gerentes de cl\u00ednicas veterinarias y divulgamos parte del trabajo que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3687,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:heading {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<h2>La opini\u00f3n de los gerentes de cl\u00ednicas veterinarias<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>La empresa de servicios de gesti\u00f3n estrat\u00e9gica y marketing digital Myvetpet Consulting entrevista a \u00c1lvaro Molins, gerente de Cl\u00ednica Veterinaria Veteros de Barcelona que forma parte del Grupo Riera Alta. Mediante esta entrevista damos voz a los gerentes de cl\u00ednicas veterinarias y divulgamos parte del trabajo que realizan al frente de sus negocios, poniendo en valor el esfuerzo diario que exige esta dif\u00edcil profesi\u00f3n y que hacen de la veterinaria un servicio esencial para la sociedad moderna.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet - La vocaci\u00f3n<\/strong><br><strong>\u00bfCu\u00e1ndo decidiste que quer\u00edas ser gerente de una cl\u00ednica veterinaria y c\u00f3mo se materializ\u00f3?<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Empec\u00e9 a estudiar ATV motivado por mi hermano mayor. Tuve mucha suerte y enseguida me cogieron en el Hospital Veterinario Riera Alta, d\u00f3nde aprend\u00ed y disfrut\u00e9 muchos a\u00f1os haciendo mi labor. Con el tiempo pens\u00e9 en dar un paso m\u00e1s all\u00e1 y fue cuando habl\u00e9 con el director de Grup Riera Alta y abrimos la posibilidad de emprender hacia una nueva etapa. Yo estuve mirando muchos traspasos y con su experiencia me ayud\u00f3 a escoger la mejor opci\u00f3n y tomar la decisi\u00f3n de seleccionar la cl\u00ednica veterinaria Veteros. Desde entonces ha llovido un poco, pero seguimos con la misma ilusi\u00f3n del primer d\u00eda.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet -&nbsp;La cl\u00ednica<\/strong><br><strong>\u00bfPor qu\u00e9 decides instalar una cl\u00ednica veterinaria en Barcelona?<br>Cu\u00e9ntanos que cambios has realizado desde los inicios y que servicios ofreces actualmente a tus clientes.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Decidimos que fuera Barcelona por log\u00edstica, por aquel entonces ten\u00eda mi vida establecida en Barcelona. Al principio est\u00e1bamos Yolanda y yo, pero poco a poco empezamos a ampliar la parte de tienda y el personal. Actualmente somos dos veterinarios, Yolanda y Jes\u00fas, y dos ATV, Soraya y yo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Como servicios ofrecemos todo lo necesario para mantener la mejor calidad de vida de nuestros peludines. Ya sea con consultas generales, vacunaciones, cirug\u00edas, radiolog\u00eda digital, ecograf\u00eda, anal\u00edticas completas o simplemente adquirir la mejor alimentaci\u00f3n, golosinas o juguetes para disfrutar junto a sus compa\u00f1eros humanos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:toolset-blocks\/image {\"dynamic\":{\"toolsetDSVersion\":\"230000\"},\"url\":\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-instalaciones-laboratorio-2-1.jpg\",\"captionStyle\":{\"bold\":false,\"italic\":false,\"strikethrough\":false},\"id\":3054,\"lightbox\":{\"enabled\":false,\"group\":null}} -->\n[tb-dynamic-container provider='' source='' field='' removeDeadLinkTarget=\"true\"]<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"1\"><img src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-instalaciones-laboratorio-2-1.jpg\" alt=\"%%tb-image-alt-text%%\" class=\"%%tb-image-wp-image-class%%\" \/><\/figure>[\/tb-dynamic-container]\n<!-- \/wp:toolset-blocks\/image --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:toolset-blocks\/image {\"dynamic\":{\"toolsetDSVersion\":\"230000\"},\"url\":\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-inicio-instalaciones-1.jpg\",\"captionStyle\":{\"bold\":false,\"italic\":false,\"strikethrough\":false},\"id\":2973,\"lightbox\":{\"enabled\":false,\"group\":null}} -->\n[tb-dynamic-container provider='' source='' field='' removeDeadLinkTarget=\"true\"]<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"1\"><img src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-inicio-instalaciones-1.jpg\" alt=\"%%tb-image-alt-text%%\" class=\"%%tb-image-wp-image-class%%\" \/><\/figure>[\/tb-dynamic-container]\n<!-- \/wp:toolset-blocks\/image -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet - El equipo<\/strong><br><strong>&nbsp;\u00bfCu\u00e1nto tiempo lleva el equipo contigo? \u00bfCu\u00e1les son sus funciones?<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>El equipo de Veteros est\u00e1 integrado por Yolanda Brils y Jes\u00fas \u00c1ngel Parro como veterinarios, cuyo d\u00eda a d\u00eda es pasar visitas, diagnosticar y tratar a sus pacientes para que est\u00e9n lo m\u00e1s sanos posibles. El resto del equipo lo componemos Soraya Mart\u00ed y yo (\u00c1lvaro Molins), que nos dedicamos a atender a nuestros clientes, atender a sus mascotas y ayudar en cualquier funci\u00f3n que necesiten los veterinarios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet - La gesti\u00f3n del tiempo<\/strong><br><strong>\u00bfEn qu\u00e9 consiste este \u00bfC\u00f3mo organizas las principales tareas de la cl\u00ednica veterinaria para que los clientes queden satisfechos de vuestros servicios, dedicar tiempo a la gesti\u00f3n de la empresa y adem\u00e1s hacer de pap\u00e1??<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Pues la verdad es que, como todo, al principio fue durillo y complicado. Adem\u00e1s, hay que tener en cuenta que los temas administrativos y de gesti\u00f3n me pillaba todo nuevo, pero mi socio Javier me apoy\u00f3 en todo y lo fuimos superando. A d\u00eda de hoy todo es mucho m\u00e1s f\u00e1cil gracias al gran equipo que tenemos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column {\"width\":\"100%\"} -->\n<div class=\"wp-block-column\" style=\"flex-basis:100%\"><!-- wp:toolset-blocks\/image {\"dynamic\":{\"toolsetDSVersion\":\"230000\"},\"url\":\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-inicio-equipo-1.jpg\",\"captionStyle\":{\"bold\":false,\"italic\":false,\"strikethrough\":false},\"id\":2965,\"lightbox\":{\"enabled\":false,\"group\":null}} -->\n[tb-dynamic-container provider='' source='' field='' removeDeadLinkTarget=\"true\"]<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"1\"><img src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-inicio-equipo-1.jpg\" alt=\"%%tb-image-alt-text%%\" class=\"%%tb-image-wp-image-class%%\" \/><\/figure>[\/tb-dynamic-container]\n<!-- \/wp:toolset-blocks\/image --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column {\"width\":\"100%\"} -->\n<div class=\"wp-block-column\" style=\"flex-basis:100%\"><!-- wp:toolset-blocks\/image {\"dynamic\":{\"toolsetDSVersion\":\"230000\"},\"url\":\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-instalaciones-radio-1.jpg\",\"captionStyle\":{\"bold\":false,\"italic\":false,\"strikethrough\":false},\"id\":3056,\"lightbox\":{\"enabled\":false,\"group\":null}} -->\n[tb-dynamic-container provider='' source='' field='' removeDeadLinkTarget=\"true\"]<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"1\"><img src=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2020\/03\/veteros-instalaciones-radio-1.jpg\" alt=\"%%tb-image-alt-text%%\" class=\"%%tb-image-wp-image-class%%\" \/><\/figure>[\/tb-dynamic-container]\n<!-- \/wp:toolset-blocks\/image --><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet - La gesti\u00f3n estrat\u00e9gica<\/strong><br><strong>Eres un gerente de cl\u00ednica veterinaria que sabemos dedicas parte de tu tiempo a analizar qu\u00e9 cosas pasan y por qu\u00e9 pasan en tu negocio. \u00bfQu\u00e9 beneficios te aporta dedicar parte de tu tiempo a la gesti\u00f3n estrat\u00e9gica en la cl\u00ednica veterinaria?<\/strong> <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Este es un tema muy importante. Creo que nuestros clientes tienen motivaciones y necesidades diferentes ,y es por ello por lo que intentamos estar lo m\u00e1s informados y asesorados sobre ello, para cubrirlas lo mejor posible.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet - La visibilidad en internet<br>\u00bfQu\u00e9 piensas de estar en internet? \u00bfNecesidad u obligaci\u00f3n?<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>A d\u00eda de hoy para nosotros considero que internet es una necesidad para poder transmitir toda la informaci\u00f3n veraz que requieren nuestros clientes y una obligaci\u00f3n para poder mantenerles al d\u00eda de cualquier avance de nuestro sector.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet \u2013 La comunicaci\u00f3n<br>\u00bfC\u00f3mo entiendes debe ser la comunicaci\u00f3n entre la cl\u00ednica veterinaria y los propietarios de mascotas? Hemos visto tu cl\u00ednica est\u00e1 entre las primeras de Barcelona en las excelentes opiniones que dejan vuestros clientes en internet, un 4,7 en Google es el sue\u00f1o deseado para muchos centros \u00bfC\u00f3mo lo haces?<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Nosotros siempre vamos a tratar, cuidar y informar a nuestros pacientes como si se tratase de los nuestros. Intentamos ponernos en el lugar del propietario, pero sin dejar de lado nuestro papel m\u00e1s cl\u00ednico y profesional. Buscar ese equilibrio creo es la clave.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet \u2013 El sector<br>\u00bfCu\u00e1l es tu opini\u00f3n acerca de d\u00f3nde se dirige este sector? \u00bfPiensas que estamos en una transformaci\u00f3n de este tipo de negocios hacia una mayor profesionalizaci\u00f3n?<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p>Sin duda alguna. El sector va a la par con lo que reclama una sociedad cada vez m\u00e1s consciente de los avances cient\u00edficos y de la mayor aceptaci\u00f3n de nuestras mascotas en todos los aspectos. Cada vez podemos ir con ellas a m\u00e1s sitios y nos damos cuenta de lo necesarias que son en nuestras vidas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>Myvetpet - <\/strong>Como siempre, es un placer compartir contigo un poco de ese tan valioso tiempo y te agradecemos esta aportaci\u00f3n que nos has hecho hoy.<strong><br><\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><strong>\u00c1lvaro Molins, Cl\u00ednica Veterinaria Veteros de Barcelona<br>David Vargas, Myvetpet Consulting<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons {\"contentJustification\":\"center\"} -->\n<div class=\"wp-block-buttons is-content-justification-center\"><!-- wp:button {\"dynamicAttributes\":{\"toolsetDSVersion\":\"230000\"}} \/--><\/div>\n<!-- \/wp:buttons -->","_et_gb_content_width":"","footnotes":""},"categories":[115,120],"tags":[],"class_list":["post-3686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publica-es","category-publica-es-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista a \u00c1lvaro Molins - Cl\u00ednica Veterinaria Veteros<\/title>\n<meta name=\"description\" content=\"Entrevistamos a \u00c1lvaro Molins, ATV y gerente de Veteros Cl\u00ednica Veterin\u00e0ria de Barcelona para explicarnos su experiencia en el sector.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista a \u00c1lvaro Molins - Cl\u00ednica Veterinaria Veteros\" \/>\n<meta property=\"og:description\" content=\"Entrevistamos a \u00c1lvaro Molins, ATV y gerente de Veteros Cl\u00ednica Veterin\u00e0ria de Barcelona para explicarnos su experiencia en el sector.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Veterinaria Veteros\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-29T08:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T16:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2021\/09\/AlvaroMolins-Veteros-1-e1632326089312.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"paula\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"paula\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/\"},\"author\":{\"name\":\"paula\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#\\\/schema\\\/person\\\/2d2b2014f4d1a75ba63fa7815e945dbf\"},\"headline\":\"Entrevista a \u00c1lvaro Molins\",\"datePublished\":\"2021-09-29T08:00:48+00:00\",\"dateModified\":\"2021-09-30T16:19:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/\"},\"wordCount\":1422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veterinariveteros.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AlvaroMolins-Veteros-1-e1632326089312.jpg\",\"articleSection\":[\"P\u00fablica\",\"P\u00fablica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/\",\"url\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/\",\"name\":\"Entrevista a \u00c1lvaro Molins - Cl\u00ednica Veterinaria Veteros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veterinariveteros.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AlvaroMolins-Veteros-1-e1632326089312.jpg\",\"datePublished\":\"2021-09-29T08:00:48+00:00\",\"dateModified\":\"2021-09-30T16:19:15+00:00\",\"description\":\"Entrevistamos a \u00c1lvaro Molins, ATV y gerente de Veteros Cl\u00ednica Veterin\u00e0ria de Barcelona para explicarnos su experiencia en el sector.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veterinariveteros.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AlvaroMolins-Veteros-1-e1632326089312.jpg\",\"contentUrl\":\"https:\\\/\\\/veterinariveteros.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AlvaroMolins-Veteros-1-e1632326089312.jpg\",\"width\":1000,\"height\":665,\"caption\":\"Alvaro Molins Veteros\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/blog\\\/2021\\\/09\\\/29\\\/entrevista-a-alvaro-molins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista a \u00c1lvaro Molins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/\",\"name\":\"Cl\u00ednica Veterinaria Veteros\",\"description\":\"Cl\u00ednica Veterinaria Veteros\",\"publisher\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#organization\",\"name\":\"Centre Veterinari Veteros\",\"url\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veterinariveteros.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Grup-Riera-alta-Logotipo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/veterinariveteros.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Grup-Riera-alta-Logotipo-1.jpg\",\"width\":468,\"height\":138,\"caption\":\"Centre Veterinari Veteros\"},\"image\":{\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veterinariveteros.com\\\/es\\\/#\\\/schema\\\/person\\\/2d2b2014f4d1a75ba63fa7815e945dbf\",\"name\":\"paula\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c6eb6381c237a1953a9be09d8c289d4ff784b5e35a57f3ed2548fc8fbd84595?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c6eb6381c237a1953a9be09d8c289d4ff784b5e35a57f3ed2548fc8fbd84595?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c6eb6381c237a1953a9be09d8c289d4ff784b5e35a57f3ed2548fc8fbd84595?s=96&d=mm&r=g\",\"caption\":\"paula\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista a \u00c1lvaro Molins - Cl\u00ednica Veterinaria Veteros","description":"Entrevistamos a \u00c1lvaro Molins, ATV y gerente de Veteros Cl\u00ednica Veterin\u00e0ria de Barcelona para explicarnos su experiencia en el sector.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista a \u00c1lvaro Molins - Cl\u00ednica Veterinaria Veteros","og_description":"Entrevistamos a \u00c1lvaro Molins, ATV y gerente de Veteros Cl\u00ednica Veterin\u00e0ria de Barcelona para explicarnos su experiencia en el sector.","og_url":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/","og_site_name":"Cl\u00ednica Veterinaria Veteros","article_published_time":"2021-09-29T08:00:48+00:00","article_modified_time":"2021-09-30T16:19:15+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2021\/09\/AlvaroMolins-Veteros-1-e1632326089312.jpg","type":"image\/jpeg"}],"author":"paula","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"paula","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#article","isPartOf":{"@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/"},"author":{"name":"paula","@id":"https:\/\/veterinariveteros.com\/es\/#\/schema\/person\/2d2b2014f4d1a75ba63fa7815e945dbf"},"headline":"Entrevista a \u00c1lvaro Molins","datePublished":"2021-09-29T08:00:48+00:00","dateModified":"2021-09-30T16:19:15+00:00","mainEntityOfPage":{"@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/"},"wordCount":1422,"commentCount":0,"publisher":{"@id":"https:\/\/veterinariveteros.com\/es\/#organization"},"image":{"@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#primaryimage"},"thumbnailUrl":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2021\/09\/AlvaroMolins-Veteros-1-e1632326089312.jpg","articleSection":["P\u00fablica","P\u00fablica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/","url":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/","name":"Entrevista a \u00c1lvaro Molins - Cl\u00ednica Veterinaria Veteros","isPartOf":{"@id":"https:\/\/veterinariveteros.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#primaryimage"},"image":{"@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#primaryimage"},"thumbnailUrl":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2021\/09\/AlvaroMolins-Veteros-1-e1632326089312.jpg","datePublished":"2021-09-29T08:00:48+00:00","dateModified":"2021-09-30T16:19:15+00:00","description":"Entrevistamos a \u00c1lvaro Molins, ATV y gerente de Veteros Cl\u00ednica Veterin\u00e0ria de Barcelona para explicarnos su experiencia en el sector.","breadcrumb":{"@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#primaryimage","url":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2021\/09\/AlvaroMolins-Veteros-1-e1632326089312.jpg","contentUrl":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2021\/09\/AlvaroMolins-Veteros-1-e1632326089312.jpg","width":1000,"height":665,"caption":"Alvaro Molins Veteros"},{"@type":"BreadcrumbList","@id":"https:\/\/veterinariveteros.com\/es\/blog\/2021\/09\/29\/entrevista-a-alvaro-molins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veterinariveteros.com\/es\/"},{"@type":"ListItem","position":2,"name":"Entrevista a \u00c1lvaro Molins"}]},{"@type":"WebSite","@id":"https:\/\/veterinariveteros.com\/es\/#website","url":"https:\/\/veterinariveteros.com\/es\/","name":"Cl\u00ednica Veterinaria Veteros","description":"Cl\u00ednica Veterinaria Veteros","publisher":{"@id":"https:\/\/veterinariveteros.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veterinariveteros.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veterinariveteros.com\/es\/#organization","name":"Centre Veterinari Veteros","url":"https:\/\/veterinariveteros.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veterinariveteros.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2019\/11\/Grup-Riera-alta-Logotipo-1.jpg","contentUrl":"https:\/\/veterinariveteros.com\/wp-content\/uploads\/2019\/11\/Grup-Riera-alta-Logotipo-1.jpg","width":468,"height":138,"caption":"Centre Veterinari Veteros"},"image":{"@id":"https:\/\/veterinariveteros.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/veterinariveteros.com\/es\/#\/schema\/person\/2d2b2014f4d1a75ba63fa7815e945dbf","name":"paula","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c6eb6381c237a1953a9be09d8c289d4ff784b5e35a57f3ed2548fc8fbd84595?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c6eb6381c237a1953a9be09d8c289d4ff784b5e35a57f3ed2548fc8fbd84595?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c6eb6381c237a1953a9be09d8c289d4ff784b5e35a57f3ed2548fc8fbd84595?s=96&d=mm&r=g","caption":"paula"}}]}},"_links":{"self":[{"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/posts\/3686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/comments?post=3686"}],"version-history":[{"count":0,"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/posts\/3686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/media\/3687"}],"wp:attachment":[{"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/media?parent=3686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/categories?post=3686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veterinariveteros.com\/es\/wp-json\/wp\/v2\/tags?post=3686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}